{"id":57391,"date":"2022-04-28T19:51:50","date_gmt":"2022-04-28T17:51:50","guid":{"rendered":"https:\/\/www.geneveroule.ch\/integration-and-asylum\/"},"modified":"2022-05-06T10:56:36","modified_gmt":"2022-05-06T08:56:36","slug":"integration-and-asylum","status":"publish","type":"page","link":"https:\/\/www.geneveroule.ch\/en\/integration-and-asylum\/","title":{"rendered":"Integration and asylum"},"content":{"rendered":"\n[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FBBA00&#8243; height=&#8221;100px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;-30px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; animation_style=&#8221;bounce&#8221; global_colors_info=&#8221;{}&#8221; button_text_color__hover=&#8221;#E52629&#8243; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#FBBA00&#8243; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_border_radius__hover=&#8221;35px&#8221; button_border_radius__hover_enabled=&#8221;on|hover&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Saune Bold||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin_tablet=&#8221;10px|||40px|false|false&#8221; custom_margin_phone=&#8221;11px|||15px|false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<h1 style=\"text-align: left;\"><span style=\"color: #ffffff;\">Int\u00e9gration et asile\n<\/span><\/h1>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.geneveroule.ch\/wp-content\/uploads\/2021\/11\/Picto_ConseilEmploi.png&#8221; alt=&#8221;Picto_ConseilEmploi&#8221; title_text=&#8221;Picto_ConseilEmploi&#8221; align=&#8221;right&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; height=&#8221;150px&#8221; height_tablet=&#8221;100px&#8221; height_phone=&#8221;80px&#8221; height_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;10px||||false|false&#8221; custom_margin_tablet=&#8221;-62px||||false|false&#8221; custom_margin_phone=&#8221;-42px|-10px|||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;-100px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][lwp_divi_breadcrumbs home_text=&#8221;Accueil&#8221; link_color=&#8221;#3023AD&#8221; separator_color=&#8221;#FBBA00&#8243; current_text_color=&#8221;#FBBA00&#8243; disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; module_font=&#8221;|300|||||||&#8221; module_text_align=&#8221;left&#8221; module_text_color=&#8221;#FBBA00&#8243; module_font_size=&#8221;16px&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;right&#8221; custom_margin=&#8221;14px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/lwp_divi_breadcrumbs][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||-30px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; title_text_tablet=&#8221;upholsterer-41&#8243;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;63.9%&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; header_2_font_size=&#8221;42px&#8221; custom_margin=&#8221;50px||50px||false|false&#8221; custom_margin_tablet=&#8221;50px||50px||false|false&#8221; custom_margin_phone=&#8221;0px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;|11%||11%|false|true&#8221; custom_padding_tablet=&#8221;|11%||11%|false|true&#8221; custom_padding_phone=&#8221;|10px||10px|false|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<h2 style=\"text-align: center;\">Les d\u00e9fis de l&#8217;int\u00e9gration professionnelle des r\u00e9fugi\u00e9-e-s et requ\u00e9rant-e-s d&#8217;asile en Suisse romande : l&#8217;exp\u00e9rience de Gen\u00e8veroule<\/h2>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|||50px|false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<h4 style=\"text-align: left;\"><span style=\"color: #fbba00;\">Une analyse de Kristela Tepelena, sociologue et collaboratrice au Conseil emploi de Gen\u00e8veroule<\/span><span style=\"color: #fbba00;\"><\/span><span style=\"color: #fbba00;\">\u00a0<\/span><\/h4>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.geneveroule.ch\/wp-content\/uploads\/2021\/12\/Insertion-emploi-mecanique.jpg&#8221; alt=&#8221;Insertion emploi-m\u00e9canique&#8221; title_text=&#8221;Insertion emploi-m\u00e9canique&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_color=&#8221;#FBBA00&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: center;\">Gennaro Capuano, responsable des arcades et ateliers et Kamal Ali, m\u00e9canicien AdR<br \/>Photo: Sigfredo Haro<\/p>[\/et_pb_text][et_pb_icon font_icon=&#8221;&#x7c;||divi||400&#8243; icon_color=&#8221;#FBBA00&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;||-45px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_icon][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;60px|60px|50px|60px|false|true&#8221; custom_padding_tablet=&#8221;60px|60px|50px|60px|false|true&#8221; custom_padding_phone=&#8221;60px|15px|50px|15px|false|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; global_colors_info=&#8221;{}&#8221;]<p><em>&#8220;<\/em><em>\u00c7a fait un moment que mon objectif principal est celui de trouver un emploi, qui correspondrait \u00e0 mes d\u00e9sirs et valeurs. Un emploi qui me motiverait d\u2019aller de l\u2019avant et qui me ferait vibrer. Pourtant, c\u2019est dur. Malgr\u00e9 mes nombreuses postulations, et malgr\u00e9 mon CV bien riche, j\u2019arrive \u00e0 peine \u00e0 d\u00e9crocher des entretiens d\u2019embauche. Je ne me voile pas la face et je pense que mon permis (N) constitue un \u00e9norme frein pour moi. M\u00eame si selon la loi suisse, c\u2019est un permis valable pour exercer une activit\u00e9 lucrative, je crois que les employeurs-euses ne veulent pas se casser trop la t\u00eate avec plus de d\u00e9marches administratives ou peut-\u00eatre car \u00e7a reste quand m\u00eame un permis provisoire. Je ne veux pas trop penser n\u00e9gativement \u00e0 d\u2019autres raisons de pourquoi ils ou elles ne m\u2019embauchent pas. Je ne veux pas penser aux diff\u00e9rentes discriminations qui peuvent \u00eatre pr\u00e9sentes dans les pens\u00e9es de chacun et chacune car sinon je me d\u00e9motive, et je n\u2019aurais plus la force de continuer \u00e0 me battre. <\/em><\/p>\n<p><em>Je sais qu\u2019une seule chose\u00a0: je veux travailler, je veux avoir mon propre salaire et ne plus recevoir des prestations sociales. Je veux absolument aider et participer \u00e0 la vie \u00e9conomique du canton genevois, et aussi au bien-\u00eatre g\u00e9n\u00e9ral de la population. J\u2019esp\u00e8re que mon exp\u00e9rience professionnelle au sein de l\u2019\u00e9quipe de Gen\u00e8veroule servira comme tremplin pour acc\u00e9der au march\u00e9 du travail genevois. Je me sens d\u2019une certaine fa\u00e7on redevable \u00e0 ce pays qui m\u2019a h\u00e9berg\u00e9 dans des moments extr\u00eamement difficiles, et donner ma contribution modeste serait la moindre des choses que je puisse faire. <\/em>\u201d<\/p>\n<p style=\"text-align: right;\"><em><strong class=\"et_pb_testimonial_author et-fb-editable-element et-fb-editable-element__editing\" data-shortcode-id=\"5.0.1.0-1640018894949\" data-quickaccess-id=\"author\" data-quickaccess-order=\"1\">Une collaboratrice de Gen\u00e8veroule<\/strong><\/em><\/p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p>L\u2019int\u00e9gration des populations issues de la migration est un sujet majeur et un r\u00e9el d\u00e9fi dans le canton genevois. Les chercheurs-euses en sciences sociales estiment que l\u2019exercice d\u2019une activit\u00e9 lucrative constituerait le principal vecteur d\u2019int\u00e9gration en Suisse romande. Il a \u00e9t\u00e9 amplement d\u00e9montr\u00e9 que les tentatives d\u2019int\u00e9gration des requ\u00e9rant-e-s d\u2019asile et les r\u00e9fugi\u00e9-e-s sont perturb\u00e9es non seulement en comparaison avec les natif-ves, mais \u00e9galement avec les autres cat\u00e9gories de migrant-e-s. Cela est \u00e9galement visible dans le t\u00e9moignage d\u2019une des collaboratrices de Gen\u00e8veroule pr\u00e9sent\u00e9 au d\u00e9but de cet article.<\/p>\n<p>Les requ\u00e9rant-e-s d\u2019asile et les r\u00e9fugi\u00e9-e-s se heurtent \u00e0 des discriminations en raison de leur permis de s\u00e9jour, du label provisoire de leurs permis, d\u2019un capital humain moins adapt\u00e9 aux besoins \u00e9conomiques de la Suisse, ainsi que du manque d\u2019information pour trouver un emploi en ad\u00e9quation avec leurs qualifications. En r\u00e9sum\u00e9, les barri\u00e8res que cette population peut rencontrer se regroupent en trois groupes de facteurs :<\/p>\n<p><strong>1)<\/strong> <strong>Les facteurs structurels ou les rigidit\u00e9s institutionnelles<\/strong>, telles que la politique d\u2019int\u00e9gration, le caract\u00e8re provisoire des permis de s\u00e9jour, la non-reconnaissance des dipl\u00f4mes et\/ou l\u2019exp\u00e9rience professionnelle exerc\u00e9e \u00e0 l\u2019\u00e9tranger, ainsi que diverses formes de discriminations et des st\u00e9r\u00e9otypes fortement ancr\u00e9s dans les repr\u00e9sentations des employeurs-euses. \u00c0 cela s\u2019ajoute le fait que la restriction au march\u00e9 du travail pendant la proc\u00e9dure d\u2019asile provoque des r\u00e9percussions professionnelles pour les requ\u00e9rant-e-s d\u2019asile qui sont autoris\u00e9-e-s \u00e0 travailler seulement s\u2019il n\u2019y a pas de candidat-e-s suisses-esses ou poss\u00e9dant un permis de s\u00e9jour B ou C.<\/p>\n<p><strong>2) Les facteurs linguistiques ou culturels<\/strong> : la ma\u00eetrise de la langue du canton (dans ce cas-ci le fran\u00e7ais) demeure primordiale afin d\u2019acc\u00e9der au march\u00e9 du travail. Conna\u00eetre la langue fran\u00e7aise est \u00e9galement essentiel afin de d\u00e9velopper le r\u00e9seau et pour comprendre les documents administratifs et l\u00e9gislatifs qui seraient en leur faveur. De plus, le manque d\u2019information au sujet des codes et normes sur la r\u00e9glementation du march\u00e9 du travail genevois, le d\u00e9roulement des entretiens d\u2019embauche, la r\u00e9daction d\u2019un CV et d\u2019une lettre de motivation suisse, peuvent \u00eatre des \u00e9l\u00e9ments qui impactent l\u2019insertion professionnelle des r\u00e9fugi\u00e9-e-s et des requ\u00e9rant-e-s d\u2019asile.<\/p>\n<p><strong>3) Les facteurs psychologiques<\/strong> : de nombreuses \u00e9tudes t\u00e9moignent de la fragilit\u00e9 mentale due aux traumatismes \u00e0 la suite d\u2019\u00e9v\u00e8nements dramatiques, la situation de pr\u00e9carit\u00e9 en Suisse, ainsi que d\u2019un potentiel d\u00e9classement social.<\/p>\n<p>&nbsp;<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#F2F2F2&#8243; global_colors_info=&#8221;{}&#8221; title_text_tablet=&#8221;upholsterer-41&#8243;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|||50px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<h4><span style=\"color: #fbba00;\">Les politiques d&#8217;int\u00e9gration en Suisse et \u00e0 Gen\u00e8ve<\/span><\/h4>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p>A partir des ann\u00e9es 90\u2019, l\u2019int\u00e9gration des migrant-e-s et des r\u00e9fugi\u00e9-e-s en Suisse est devenue un enjeu essentiel relevant de la responsabilit\u00e9 de l\u2019\u00c9tat afin d\u2019assurer la bienveillance entre les Suisses-esses et les migrant-e-s, mais aussi pour r\u00e9duire le recours de ces derniers-\u00e8res \u00e0 l\u2019aide sociale. L\u2019\u00a0\u00ab\u00a0immigrant policy\u00a0\u00bb, la politique d\u2019int\u00e9gration en Suisse, comprend un ensemble de mesures et de lois ayant pour objectif principal la protection sociale et l\u00e9gale ainsi que l\u2019int\u00e9gration \u00e9conomique, culturelle et politique des migrant-e-s dans tous les domaines de la soci\u00e9t\u00e9 suisse. \u00c9tant un pays f\u00e9d\u00e9ral, il est important de pr\u00e9ciser que la politique d\u2019int\u00e9gration en Suisse fonctionne sur trois niveaux : f\u00e9d\u00e9ral, cantonal et communal. Malgr\u00e9 l\u2019existence d\u2019un cadre l\u00e9gal commun, il y a des fortes variations en mati\u00e8re d\u2019application des politiques d\u2019int\u00e9gration entre les cantons latins et germanophones.<\/p>\n<p>A Gen\u00e8ve, c\u2019est le <a href=\"https:\/\/www.ge.ch\/dossier\/geneve-soutient-integration-etrangers\" target=\"_blank\" rel=\"noopener\">Bureau de l\u2019int\u00e9gration des \u00e9trangers<\/a> (BIE) qui prend en charge l\u2019application des politiques d\u2019int\u00e9gration et leur mise en \u0153uvre. En 2014, le BIE a mis en place le <a href=\"https:\/\/www.ge.ch\/dossier\/geneve-soutient-integration-etrangers\/programme-integration-cantonal\/programme-integration-cantonal-2018-2021\" target=\"_blank\" rel=\"noopener\">Programme d\u2019int\u00e9gration cantonal<\/a> (PIC), qui propose une vari\u00e9t\u00e9 de mesures pour promouvoir la coh\u00e9sion sociale et soutenir l\u2019int\u00e9gration des migrant-e-s. Plus particuli\u00e8rement, le PIC accorde une grande importance aux mesures li\u00e9s \u00e0 l\u2019employabilit\u00e9. De nombreux partenaires institutionnels, acteurs associatifs et communaux collaborent afin de renforcer les mesures concernant la formation, les cours de langue, les cours sur les us et coutumes suisses, la formation de courte ou longue dur\u00e9e ou encore la reconnaissance des dipl\u00f4mes et les certificats des pays d\u2019origine.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|||50px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<h4><span style=\"color: #fbba00;\">La mission d&#8217;insertion de Gen\u00e8veroule<\/span><\/h4>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p>En tant qu\u2019association \u00e0 but non lucratif, Gen\u00e8veroule est un des acteurs impliqu\u00e9 dans les questions d\u2019int\u00e9gration socio-professionnelle des populations vuln\u00e9rables. Reconnue plus g\u00e9n\u00e9ralement pour la promotion de la mobilit\u00e9 douce, Gen\u00e8veroule a \u00e9galement comme mission l\u2019<a href=\"https:\/\/www.geneveroule.ch\/fr\/insertion\/\" target=\"_blank\" rel=\"noopener\">insertion socio-professionnelle<\/a> de cinq groupes cibles : les requ\u00e9rant-e-s d\u2019asile, les r\u00e9fugi\u00e9-e-s, les personnes en emploi de solidarit\u00e9, les apprenti-e-s et les pr\u00e9 apprenti-e-s, et les ch\u00f4meurs-euses en fin de droit. La mission d\u2019insertion de Gen\u00e8veroule s\u2019articule sur trois axes : la pratique professionnelle, la formation et le conseil en insertion. En effet, l\u2019obtention d\u2019un certificat de travail, l\u2019attestation de comp\u00e9tences, et un dossier de candidature complet gr\u00e2ce au service <a href=\"https:\/\/www.geneveroule.ch\/fr\/conseil-emploi\/\" target=\"_blank\" rel=\"noopener\">Conseil emploi<\/a>, concourent \u00e0 d\u00e9velopper la capacit\u00e9 d\u2019une personne \u00e0 atteindre son objectif d\u2019insertion.<\/p>\n<p>En 2021, Gen\u00e8veroule a compt\u00e9 au sein de son \u00e9quipe plus de 60 r\u00e9fugi\u00e9-e-s et requ\u00e9rant-e-s d\u2019asile qui travaillent, suivent un stage ou une formation. L\u2019id\u00e9e principale est de \u00ab travailler pour se r\u00e9ins\u00e9rer \u00bb. Donc, donner la possibilit\u00e9 \u00e0 cette population d\u2019avoir une exp\u00e9rience professionnelle concr\u00e8te et valorisante afin de regagner la confiance en soi, se former, apprendre les normes et les codes d\u2019un emploi en Suisse, et se rapprocher le plus possible d\u2019un poste de travail ad\u00e9quat avec leurs qualifications. Plus concr\u00e8tement, Gen\u00e8veroule propose des postes de 50% \u00e0 100% dans le cadre des programmes cantonaux (Office cantonal de l\u2019emploi, Hospice g\u00e9n\u00e9ral). Nous pouvons mentionner ici les activit\u00e9s de r\u00e9insertion (AdR), qui permettent de faire face aux exigences professionnelles, de mettre \u00e0 jour un CV, de cr\u00e9er du r\u00e9seau et de gagner confiance en soi. Une autre possibilit\u00e9, c\u2019est le Stage de d\u00e9veloppement de l\u2019employabilit\u00e9 (STADEVE), o\u00f9 les stagiaires b\u00e9n\u00e9ficient d\u2019une exp\u00e9rience professionnelle concr\u00e8te et d\u2019un accompagnement socio-professionnel afin de r\u00e9aliser leur propre projet professionnel.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#F2F2F2&#8243; global_colors_info=&#8221;{}&#8221; title_text_tablet=&#8221;upholsterer-41&#8243;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|||50px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<h4><span style=\"color: #fbba00;\">Embaucher une personne ayant un permis N ou F<\/span><\/h4>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p>D\u2019apr\u00e8s de nombreuses recherches en sciences sociales et selon notre propre constat, un autre \u00e9l\u00e9ment \u00e0 ne pas sous-estimer au sujet de l\u2019int\u00e9gration professionnelle des r\u00e9fugi\u00e9-e-s et des requ\u00e9rant-e-s d\u2019asile, c\u2019est la m\u00e9connaissance de la part des employeurs-euses. Embaucher une personne b\u00e9n\u00e9ficiaire d\u2019un permis N, F r\u00e9fugi\u00e9, F admis provisoire, et B r\u00e9fugi\u00e9 se r\u00e9v\u00e8le \u00eatre un sujet tabou et pas commun. De plus, la majorit\u00e9 des offres d\u2019emploi sur internet ne poss\u00e8de pas l\u2019option du permis N. Malgr\u00e9 la bonne volont\u00e9 de cette population de s\u2019engager dans la vie lucrative et de devenir ind\u00e9pendante de l\u2019aide sociale, la r\u00e9ticence de la part des employeurs-euses constitue une barri\u00e8re importante.<\/p>\n<p>Il est important de mettre en lumi\u00e8re que le fait d\u2019embaucher un-e r\u00e9fugi\u00e9-e ou un-e requ\u00e9rant-e d\u2019asile est possible et demeure une r\u00e9alit\u00e9 incontestable. De plus, c\u2019est une proc\u00e9dure facile et qui ne demande pas beaucoup de temps, contrairement \u00e0 ce qu\u2019on pourrait croire. Effectivement, la nouvelle loi sur les \u00e9trangers et l\u2019int\u00e9gration (LEI) permet une simplification des proc\u00e9dures de prise de l\u2019emploi. Cette nouvelle loi est entr\u00e9e en vigueur car les autorit\u00e9s comp\u00e9tentes ont remarqu\u00e9 qu\u2019il y avait une r\u00e9duction des co\u00fbts de l\u2019assistance publique. De plus, les employeurs-euses qui ont engag\u00e9 cette population sont tr\u00e8s satisfait-e-s du travail fourni.<\/p>\n<p>Pour engager une personne titulaire d\u2019un permis B (r\u00e9fugi\u00e9-e) ou F, il suffit de <a href=\"https:\/\/refugeesatwork.ch\/formulaire\/\" target=\"_blank\" rel=\"noopener\">remplir un formulaire<\/a> et de l\u2019envoyer \u00e0 l\u2019autorit\u00e9 comp\u00e9tente. Pour les personnes titulaires d\u2019un permis N, l\u2019exigence d\u2019une autorit\u00e9 pr\u00e9alable reste en vigueur. En effet, un-e employeur-euse qui accepte d\u2019engager une personne ayant un permis N doit demander pr\u00e9alablement une autorisation \u00e0 l\u2019Office cantonal de l&#8217;inspection et des relations du travail (OCIRT).<\/p>\n<p>Comme nous l&#8217;avons mentionn\u00e9 \u00e0 plusieurs reprises, exercer une activit\u00e9 lucrative constitue une \u00ab preuve \u00bb d&#8217;int\u00e9gration et une tr\u00e8s belle opportunit\u00e9 d&#8217;enrichissement du propre parcours professionnel pour le-la r\u00e9fugi\u00e9-e et le-la requ\u00e9rant-e d&#8217;asile. Toutefois, les aspects positifs peuvent \u00eatre soulign\u00e9s pour l\u2019employeur-euse et l\u2019entreprise qui souhaite engager une personne relevant du domaine de l&#8217;asile. Les \u00e9tudes montrent que la diversit\u00e9 et la mixit\u00e9 au sein d&#8217;un environnement de travail augmente l&#8217;innovation et permet d&#8217;\u00e9largir le regard. Venant d&#8217;une autre culture, les r\u00e9fugi\u00e9-e-s et les requ\u00e9rant-e-s d&#8217;asile peuvent apporter des nouvelles id\u00e9es et contribuer \u00e0 l&#8217;enrichissement au sein d&#8217;une \u00e9quipe. Un des m\u00e9caniciens encadrants nous en parle plus en d\u00e9tails :<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_icon font_icon=&#8221;&#x7c;||divi||400&#8243; icon_color=&#8221;#FBBA00&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;||-45px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_icon][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#F2F2F2&#8243; custom_padding=&#8221;60px|60px|50px|60px|false|true&#8221; custom_padding_tablet=&#8221;60px|60px|50px|60px|false|true&#8221; custom_padding_phone=&#8221;60px|15px|50px|15px|false|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|12px|12px|12px|12px&#8221; global_colors_info=&#8221;{}&#8221;]<p><em>\u201cUne des choses positives de travailler avec les r\u00e9fugi\u00e9-e-s c\u2019est qu\u2019on apprend d\u2019autres cultures, d\u2019autres mani\u00e8res de voir la mission du travail. M\u00eame malgr\u00e9 le fait qu\u2019ils ne parlent pas beaucoup fran\u00e7ais ou qu\u2019ils ont un probl\u00e8me avec la langue. Mais, si nous, de l\u2019autre c\u00f4t\u00e9, on fait l\u2019effort de les comprendre et avoir la patience de travailler avec eux, on arrive \u00e0 apprendre beaucoup de choses et des visions diff\u00e9rentes au niveau du travail. Je suis content et satisfait d\u2019avoir engag\u00e9 des r\u00e9fugi\u00e9s et j\u2019ai d\u00e9couvert que j\u2019ai un c\u00f4t\u00e9 humain que je ne pensais pas avoir. Quand on doit travailler avec les r\u00e9fugi\u00e9s, il faut les aider, il faut \u00eatre l\u00e0 pour eux, il faut les motiver aussi.\u201d <\/em><\/p>\n<p style=\"text-align: right;\"><em><strong class=\"et_pb_testimonial_author et-fb-editable-element et-fb-editable-element__editing\" data-shortcode-id=\"5.0.1.0-1640018894949\" data-quickaccess-id=\"author\" data-quickaccess-order=\"1\">M\u00e9canicien encadrant Gen\u00e8veroule<\/strong><\/em><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#F2F2F2&#8243; global_colors_info=&#8221;{}&#8221; title_text_tablet=&#8221;upholsterer-41&#8243;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|||50px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<h4><span style=\"color: #fbba00;\">Pour aller plus loin<\/span><\/h4>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p>Bertrand Anne-Laure (2020), <em>Dans la jungle des permis de s\u00e9jour. Parcours administratifs et int\u00e9gration professionnelle des r\u00e9fugi\u00e9s en Suisse, <\/em>Gen\u00e8ve : Seismo.<\/p>\n<p>Brell Courtney, Dustmann Christian et Preston Ian (2020), The Labor Market Integration of Refugee Migrants in High-Income Countries, <em>Journal of Economic Perspectives, <\/em>Vol.34, No.1, pp.94-121.<\/p>\n<p>Fibbi Rosita et Dahinden Janine (2004), Les requ\u00e9rants d\u2019asile et le travail : d\u00e9class\u00e9s ? indispensables ? bienvenus ?, <em>Asyl : Revue Suisse pour la pratique et le droit d\u2019asile, <\/em>No.3, pp. 21-27<\/p>\n<p>Green Eva G.T., Manatschal Anita, Pecoraro Marco et Wanner Philippe (2019), Does integration policy improve labour market, sociocultural and psychological adaptation of asylum related immigrants ? Evidence from Sri Lankans in Switzerland, <em>Institute of Economic Research,<\/em> Vol.08, No. 19, pp. 1-30.<\/p>\n<p>Hangartner Dominik et Schmid Lukas (2020), Migration, Language, and Employement, <span><a href=\"http:\/\/lukassschmid.net\/papers\">lukassschmid.net\/papers<\/a><\/span>, [en ligne], <span><a href=\"http:\/\/www.lukasschmid.net\/papers\">http:\/\/www.lukasschmid.net\/papers<\/a><\/span> (Consult\u00e9 le 2 F\u00e9vrier 2022).<\/p>\n<p>Inderm\u00fchle Yvonne, Roos Kim, Sowe Rahel et Wenger Ines (2018) Addressing barriers to work for asylum seekers : Report from Switzerland, <em>World Federation of Occupational Therapists Bulletin<\/em>, Vol.74, No.2, pp. 123-127<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Int\u00e9gration et asile <div class=\"et_pb_module lwp_divi_breadcrumbs lwp_divi_breadcrumbs_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"lwp-breadcrumbs\"> <span class=\"before\"><\/span> <span vocab=\"https:\/\/schema.org\/\" typeof=\"BreadcrumbList\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" href=\"https:\/\/www.geneveroule.ch\/en\/\" class=\"home\"><span property=\"name\">Accueil<\/span><\/a><meta property=\"position\" content=\"1\"><\/span> <span class=\"separator et-pb-icon\">&#x39;<\/span> <\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Les d\u00e9fis de l&#8217;int\u00e9gration professionnelle des r\u00e9fugi\u00e9-e-s et requ\u00e9rant-e-s d&#8217;asile en Suisse [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-57391","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The challenges of professional integration of N and F permits - Gen\u00e8veroule<\/title>\n<meta name=\"description\" content=\"Read Kristela Tepelena&#039;s analysis of the challenges of vocational integration for people in the asylum field.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geneveroule.ch\/en\/integration-and-asylum\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The challenges of professional integration of N and F permits - Gen\u00e8veroule\" \/>\n<meta property=\"og:description\" content=\"Read Kristela Tepelena&#039;s analysis of the challenges of vocational integration for people in the asylum field.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geneveroule.ch\/en\/integration-and-asylum\/\" \/>\n<meta property=\"og:site_name\" content=\"Gen\u00e8veroule\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-06T08:56:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geneveroule.ch\/wp-content\/uploads\/2021\/12\/Insertion-emploi-mecanique.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.geneveroule.ch\/wp-content\/uploads\/2021\/12\/Insertion-emploi-mecanique.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geneveroule.ch\\\/en\\\/integration-and-asylum\\\/\",\"url\":\"https:\\\/\\\/www.geneveroule.ch\\\/en\\\/integration-and-asylum\\\/\",\"name\":\"The challenges of professional integration of N and F permits - Gen\u00e8veroule\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geneveroule.ch\\\/en\\\/#website\"},\"datePublished\":\"2022-04-28T17:51:50+00:00\",\"dateModified\":\"2022-05-06T08:56:36+00:00\",\"description\":\"Read Kristela Tepelena's analysis of the challenges of vocational integration for people in the asylum field.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.geneveroule.ch\\\/en\\\/integration-and-asylum\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geneveroule.ch\\\/en\\\/integration-and-asylum\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.geneveroule.ch\\\/en\\\/integration-and-asylum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.geneveroule.ch\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Integration and asylum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geneveroule.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.geneveroule.ch\\\/en\\\/\",\"name\":\"Gen\u00e8veroule\",\"description\":\"v\u00e9lo et insertion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geneveroule.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The challenges of professional integration of N and F permits - Gen\u00e8veroule","description":"Read Kristela Tepelena's analysis of the challenges of vocational integration for people in the asylum field.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geneveroule.ch\/en\/integration-and-asylum\/","og_locale":"en_US","og_type":"article","og_title":"The challenges of professional integration of N and F permits - Gen\u00e8veroule","og_description":"Read Kristela Tepelena's analysis of the challenges of vocational integration for people in the asylum field.","og_url":"https:\/\/www.geneveroule.ch\/en\/integration-and-asylum\/","og_site_name":"Gen\u00e8veroule","article_modified_time":"2022-05-06T08:56:36+00:00","og_image":[{"url":"https:\/\/www.geneveroule.ch\/wp-content\/uploads\/2021\/12\/Insertion-emploi-mecanique.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.geneveroule.ch\/wp-content\/uploads\/2021\/12\/Insertion-emploi-mecanique.jpg","twitter_misc":{"Est. reading time":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.geneveroule.ch\/en\/integration-and-asylum\/","url":"https:\/\/www.geneveroule.ch\/en\/integration-and-asylum\/","name":"The challenges of professional integration of N and F permits - Gen\u00e8veroule","isPartOf":{"@id":"https:\/\/www.geneveroule.ch\/en\/#website"},"datePublished":"2022-04-28T17:51:50+00:00","dateModified":"2022-05-06T08:56:36+00:00","description":"Read Kristela Tepelena's analysis of the challenges of vocational integration for people in the asylum field.","breadcrumb":{"@id":"https:\/\/www.geneveroule.ch\/en\/integration-and-asylum\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geneveroule.ch\/en\/integration-and-asylum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.geneveroule.ch\/en\/integration-and-asylum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.geneveroule.ch\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Integration and asylum"}]},{"@type":"WebSite","@id":"https:\/\/www.geneveroule.ch\/en\/#website","url":"https:\/\/www.geneveroule.ch\/en\/","name":"Gen\u00e8veroule","description":"v\u00e9lo et insertion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geneveroule.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.geneveroule.ch\/en\/wp-json\/wp\/v2\/pages\/57391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geneveroule.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.geneveroule.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.geneveroule.ch\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geneveroule.ch\/en\/wp-json\/wp\/v2\/comments?post=57391"}],"version-history":[{"count":12,"href":"https:\/\/www.geneveroule.ch\/en\/wp-json\/wp\/v2\/pages\/57391\/revisions"}],"predecessor-version":[{"id":57431,"href":"https:\/\/www.geneveroule.ch\/en\/wp-json\/wp\/v2\/pages\/57391\/revisions\/57431"}],"wp:attachment":[{"href":"https:\/\/www.geneveroule.ch\/en\/wp-json\/wp\/v2\/media?parent=57391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}